{"id":710,"date":"2017-05-03T21:56:45","date_gmt":"2017-05-03T21:56:45","guid":{"rendered":"http:\/\/vcaaadev\/?page_id=710"},"modified":"2026-04-07T10:35:06","modified_gmt":"2026-04-07T17:35:06","slug":"fall-prevention","status":"publish","type":"page","link":"https:\/\/vcaaa.venturacounty.gov\/es\/our-services\/fall-prevention\/","title":{"rendered":"Prevenci\u00f3n de ca\u00eddas"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"710\" class=\"elementor elementor-710\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1700d5d4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1700d5d4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d0f679a\" data-id=\"d0f679a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dc4f011 elementor-widget elementor-widget-image\" data-id=\"dc4f011\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"275\" height=\"173\" src=\"https:\/\/vcaaa.venturacounty.gov\/wp-content\/uploads\/2022\/09\/FallPreventionProgram.jpg\" class=\"attachment-large size-large wp-image-7100\" alt=\"Fall Prevention Program logo\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a92dc31 elementor-widget elementor-widget-heading\" data-id=\"a92dc31\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">ENLACES A P\u00c1GINAS<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf061a3 elementor-widget elementor-widget-jet-custom-menu\" data-id=\"cf061a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-custom-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"menu-fall-prevention-container\"><div class=\"jet-custom-nav jet-custom-nav--dropdown-right-side jet-custom-nav--animation-fade\" data-trigger=\"hover\"><div class=\"menu-item menu-item-type-custom menu-item-object-custom jet-custom-nav__item jet-custom-nav__item-8695\"><a href=\"#fpclasses\" class=\"jet-custom-nav__item-link\"><span class=\"jet-menu-link-text\"><span class=\"jet-custom-item-label top-level-label\">Clases de prevenci\u00f3n de ca\u00eddas de VCAAA<\/span><\/span><\/a><\/div>\n<div class=\"menu-item menu-item-type-custom menu-item-object-custom jet-custom-nav__item jet-custom-nav__item-8905\"><a href=\"#nonvcaaaclasses\" class=\"jet-custom-nav__item-link\"><span class=\"jet-menu-link-text\"><span class=\"jet-custom-item-label top-level-label\">Clases de prevenci\u00f3n de ca\u00eddas no pertenecientes a la VCAAA<\/span><\/span><\/a><\/div>\n<div class=\"menu-item menu-item-type-custom menu-item-object-custom jet-custom-nav__item jet-custom-nav__item-8694\"><a href=\"#fpforum\" class=\"jet-custom-nav__item-link\"><span class=\"jet-menu-link-text\"><span class=\"jet-custom-item-label top-level-label\">Foro sobre prevenci\u00f3n de ca\u00eddas<\/span><\/span><\/a><\/div>\n<div class=\"menu-item menu-item-type-custom menu-item-object-custom jet-custom-nav__item jet-custom-nav__item-8697\"><a href=\"#fpvideos\" class=\"jet-custom-nav__item-link\"><span class=\"jet-menu-link-text\"><span class=\"jet-custom-item-label top-level-label\">V\u00eddeos de prevenci\u00f3n de ca\u00eddas<\/span><\/span><\/a><\/div>\n<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-36d2ec5d\" data-id=\"36d2ec5d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5558585 elementor-widget elementor-widget-image\" data-id=\"5558585\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"160\" src=\"https:\/\/vcaaa.venturacounty.gov\/wp-content\/uploads\/2024\/12\/FallPrevention.jpg\" class=\"attachment-large size-large wp-image-8762\" alt=\"collage of pictures of instructors and participants from Tai Chi classes\" srcset=\"https:\/\/vcaaa.venturacounty.gov\/wp-content\/uploads\/2024\/12\/FallPrevention.jpg 1000w, https:\/\/vcaaa.venturacounty.gov\/wp-content\/uploads\/2024\/12\/FallPrevention-480x96.jpg 480w, https:\/\/vcaaa.venturacounty.gov\/wp-content\/uploads\/2024\/12\/FallPrevention-768x154.jpg 768w, https:\/\/vcaaa.venturacounty.gov\/wp-content\/uploads\/2024\/12\/FallPrevention-18x4.jpg 18w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2718157e elementor-widget elementor-widget-text-editor\" data-id=\"2718157e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La Coalici\u00f3n para la Prevenci\u00f3n de Ca\u00eddas en Personas Mayores es una alianza comunitaria integrada por profesionales de la salud, servicios de emergencia, proveedores de servicios para adultos mayores y defensores de la comunidad, con el objetivo de reducir las ca\u00eddas y sus devastadoras consecuencias para los adultos mayores en el condado de Ventura.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b8f4a6 elementor-widget elementor-widget-n-accordion\" data-id=\"3b8f4a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Acorde\u00f3n. Abra los enlaces con Intro o Espacio, ci\u00e9rrelos con Escape y navegue con las teclas de flecha.\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-6240\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-6240\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> M\u00e1s informaci\u00f3n y enlaces <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-6240\" class=\"elementor-element elementor-element-4c2cefb e-con-full e-flex e-con e-child\" data-id=\"4c2cefb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fec398e elementor-widget elementor-widget-text-editor\" data-id=\"fec398e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\"\u00a0<a href=\"http:\/\/vcaaa.venturacounty.gov\/wp-content\/uploads\/2024\/02\/Fall_Prevention_Class_Flyer_2024_EN.pdf\" target=\"_blank\" rel=\"noopener\">Descripciones de las clases del programa de prevenci\u00f3n de ca\u00eddas (PDF-Ingl\u00e9s)<\/a><br \/>\"\u00a0<a href=\"http:\/\/vcaaa.venturacounty.gov\/wp-content\/uploads\/2024\/02\/Fall_Prevention_Class_Flyer_2024_SP.pdf\" target=\"_blank\" rel=\"noopener\">Descripciones de las clases del programa de prevenci\u00f3n de ca\u00eddas (PDF-Espa\u00f1ol)<\/a><br \/>\"\u00a0<a href=\"https:\/\/vcaaa.venturacounty.gov\/wp-content\/uploads\/2024\/11\/Fall-Prevention-Info-Flyer-EN-03-07-22.pdf\" target=\"_blank\" rel=\"noopener\">Consejos de seguridad en el hogar para prevenir las ca\u00eddas (PDF-Ingl\u00e9s)<\/a><br \/>\"\u00a0<a href=\"https:\/\/vcaaa.venturacounty.gov\/wp-content\/uploads\/2024\/11\/Fall-Prevention-Info-Flyer-SP-03-07-22.pdf\" target=\"_blank\" rel=\"noopener\">Consejos de seguridad en el hogar para prevenir las ca\u00eddas (PDF-Espa\u00f1ol)<\/a><\/p><p>Para m\u00e1s informaci\u00f3n, llame al 805-477-7300, opci\u00f3n 6, o env\u00ede un correo electr\u00f3nico a\u00a0<a href=\"mailto:Fall.Prevention.Program@venturacounty.gov\">Fall.Prevention.Program@venturacounty.gov<\/a>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e8d8e8a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"e8d8e8a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71e2431 elementor-widget elementor-widget-menu-anchor\" data-id=\"71e2431\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"fpclasses\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f235030 elementor-widget elementor-widget-heading\" data-id=\"f235030\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Clases de prevenci\u00f3n de ca\u00eddas de VCAAA<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d538d3c elementor-widget elementor-widget-text-editor\" data-id=\"d538d3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div><p>Vuelva a consultar esta p\u00e1gina para obtener futuras actualizaciones.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b4dec2a elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"b4dec2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div><p>Si se ha ca\u00eddo o tiene miedo de caerse, considere contactarnos para asistir a clases GRATUITAS donde aprender\u00e1 a mejorar la movilidad y el equilibrio. Para m\u00e1s informaci\u00f3n o para inscribirse en una clase, llame al 805-477-7300, opci\u00f3n 6, o env\u00ede un correo electr\u00f3nico. <a href=\"mailto:Fall.Prevention.Program@venturacounty.gov\">Fall.Prevention.Program@venturacounty.gov<\/a>.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5be410d elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-n-accordion\" data-id=\"5be410d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Acorde\u00f3n. Abra los enlaces con Intro o Espacio, ci\u00e9rrelos con Escape y navegue con las teclas de flecha.\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-9630\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-9630\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Requisitos para los cursos de prevenci\u00f3n de ca\u00eddas <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-9630\" class=\"elementor-element elementor-element-6c5043f e-flex e-con-boxed e-con e-child\" data-id=\"6c5043f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-044d5d1 elementor-widget elementor-widget-text-editor\" data-id=\"044d5d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Abierto a residentes en el condado de Ventura mayores de 60 a\u00f1os<\/li><li>Abierto a sus c\u00f3nyuges (aunque tengan menos de 60 a\u00f1os)<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d6b0a6 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"4d6b0a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Hay cinco clases, aunque es posible que no todas se ofrezcan al mismo tiempo. Haga clic en los enlaces a continuaci\u00f3n para ver las descripciones de las clases y acceder a los folletos de las pr\u00f3ximas clases.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-227109f elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-n-accordion\" data-id=\"227109f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Acorde\u00f3n. Abra los enlaces con Intro o Espacio, ci\u00e9rrelos con Escape y navegue con las teclas de flecha.\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-3610\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-3610\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Bingocize <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-3610\" class=\"elementor-element elementor-element-46d86c4 e-con-full e-flex e-con e-child\" data-id=\"46d86c4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5325c9e elementor-widget elementor-widget-text-editor\" data-id=\"5325c9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Bingocize est\u00e1 dise\u00f1ado para personas con actividad moderada que se han ca\u00eddo o han desarrollado miedo a caerse. Los participantes podr\u00e1n jugar al bingo, responder preguntas de trivia y realizar ejercicios sentados y de pie, con la disposici\u00f3n de practicar en casa. Los participantes con deterioro cognitivo leve podr\u00edan ser elegibles.<\/p><p><span style=\"color: #008080;\">\"<\/span> Pr\u00f3ximas clases por determinar<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-3611\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-3611\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Cuesti\u00f3n de equilibrio <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-3611\" class=\"elementor-element elementor-element-9f59e11 e-con-full e-flex e-con e-child\" data-id=\"9f59e11\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4625351 elementor-widget elementor-widget-text-editor\" data-id=\"4625351\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A Matter of Balance est\u00e1 dise\u00f1ado para personas poco activas que se han ca\u00eddo o han desarrollado miedo a caerse. Los participantes deben esperar un entorno basado en la conversaci\u00f3n mientras completan ejercicios para principiantes sentados y de pie. Los ejercicios se centran en mejorar el equilibrio, la fuerza, la flexibilidad y la confianza en uno mismo. Los participantes no pueden tener discapacidades cognitivas.<\/p><p><span style=\"color: #008080;\">\"<\/span> Pr\u00f3ximas clases por determinar<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-3612\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-3612\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Pisando fuerte <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-3612\" class=\"elementor-element elementor-element-ccf6402 e-con-full e-flex e-con e-child\" data-id=\"ccf6402\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a171225 elementor-widget elementor-widget-text-editor\" data-id=\"a171225\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Stepping On est\u00e1 dise\u00f1ado para personas que son de leves a moderadamente activas y se han ca\u00eddo o han desarrollado un miedo a caerse. Los participantes deben esperar un entorno basado en la conversaci\u00f3n mientras completan ejercicios de pie y sentados con el uso gradual de pesas en las piernas, tanto en clase como en casa. Los participantes no pueden tener problemas cognitivos ni depender de un andador.<strong><br \/><\/strong><\/p><p><span style=\"color: #008080;\">\"<\/span> Pr\u00f3ximas clases por determinar<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-3613\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-3613\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Caminar con facilidad <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-3613\" class=\"elementor-element elementor-element-ac643f8 e-flex e-con-boxed e-con e-child\" data-id=\"ac643f8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7e7978e elementor-widget elementor-widget-text-editor\" data-id=\"7e7978e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Walk With Ease est\u00e1 dise\u00f1ado para personas que son ligeramente activas y se han ca\u00eddo o han desarrollado miedo a caerse. Los participantes deben esperar consejos de motivaci\u00f3n sobre c\u00f3mo hacer ejercicio con artritis mientras trabajan para alcanzar su objetivo diario de caminar. Los participantes no pueden tener discapacidades cognitivas.<\/p><p><span style=\"color: #008080;\">\"<\/span> Pr\u00f3ximas clases por determinar<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-3614\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"5\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-3614\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Tai Chi: Moverse para mejorar el equilibrio <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-3614\" class=\"elementor-element elementor-element-a74254e e-flex e-con-boxed e-con e-child\" data-id=\"a74254e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4ff73d2 elementor-widget elementor-widget-text-editor\" data-id=\"4ff73d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El Tai Chi est\u00e1 dise\u00f1ado para personas moderadamente activas que se han ca\u00eddo o han desarrollado miedo a caerse. Los participantes deben realizar movimientos lentos y controlados, sentados o de pie. Los ejercicios se centran en mejorar la fuerza, la resistencia, el equilibrio y la conciencia corporal. Los participantes no pueden tener deterioro cognitivo.<strong><br \/><\/strong><\/p><p><span style=\"color: #008080;\">\"<\/span> Pr\u00f3ximas clases por determinar<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f4728d7 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f4728d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-81e4985 elementor-widget elementor-widget-menu-anchor\" data-id=\"81e4985\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"nonvcaaaclasses\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2a04ad elementor-widget elementor-widget-heading\" data-id=\"b2a04ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Clases de prevenci\u00f3n de ca\u00eddas no pertenecientes a la VCAAA<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d305d15 elementor-widget elementor-widget-text-editor\" data-id=\"d305d15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"wpb_text_column wpb_content_element\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column wpb_content_element\"><div class=\"wpb_wrapper\"><p>Muchas ciudades, centros para personas mayores u otras organizaciones locales tambi\u00e9n ofrecen clases para prevenir ca\u00eddas.<\/p><p>Algunos de ellos incluyen:<br \/><span style=\"color: #008080;\">\" <\/span><a href=\"https:\/\/www.camhealth.com\/activate-your-health-with-our-fall-prevention-programs\" target=\"_blank\" rel=\"noopener\">Distrito Sanitario de Camarillo<\/a><br \/><span style=\"color: #008080;\">\" <\/span><a href=\"https:\/\/www.oxnard.gov\/cultural-community-services\/recreation-community-services\/senior-programs-services\" target=\"_blank\" rel=\"noopener\">Ciudad de Oxnard<\/a><br \/><span style=\"color: #008080;\">\" <a href=\"https:\/\/www.cityofventura.ca.gov\/669\/Senior-Services\" target=\"_blank\" rel=\"noopener\">Parques y recreaci\u00f3n de la ciudad de Ventura<\/a><br \/>\" <\/span><a href=\"https:\/\/www.crpd.org\/program-registration\" target=\"_blank\" rel=\"noopener\">Distrito de Recreaci\u00f3n y Parques de Conejo<\/a><br \/><span style=\"color: #008080;\">\" <\/span><a href=\"https:\/\/www.simivalley.org\/departments\/city-manager-s-office\/community-programs-and-facilities\/senior-center\/events-programs\" target=\"_blank\" rel=\"noopener\">Centro de Mayores de Simi Valley<\/a><\/p><p>Puede encontrar m\u00e1s informaci\u00f3n y sitios visitando el <a href=\"https:\/\/www.cahealthierliving.org\/?cstcounty=ventura-2\" target=\"_blank\" rel=\"noopener\">Coalici\u00f3n para una Vida M\u00e1s Saludable en California<\/a>.<\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cbe2c2f elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"cbe2c2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24dc780 elementor-widget elementor-widget-menu-anchor\" data-id=\"24dc780\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"fpforum\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3fb31b elementor-widget elementor-widget-heading\" data-id=\"e3fb31b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Foro sobre prevenci\u00f3n de ca\u00eddas<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c81c4a elementor-widget elementor-widget-text-editor\" data-id=\"6c81c4a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El Foro de Prevenci\u00f3n de Ca\u00eddas de 2025 fue organizado por <a href=\"https:\/\/fire.venturacounty.gov\/senior-citizen-safety\/\" target=\"_blank\" rel=\"noopener\">Departamento de Bomberos del Condado de Ventura<\/a> el 26 de septiembre.\u00a0<\/p><p>\u00a0<span style=\"color: #008080;\">\" <\/span><a style=\"background-color: #ffffff;\" href=\"\/es\/our-services\/fall-prevention\/fall-prevention-forum\/\" data-uw-rm-brl=\"PR\" data-uw-original-href=\"https:\/\/vcaaa.venturacounty.gov\/our-services\/fall-prevention\/fall-prevention-forum\/\">Archivos del Foro de prevenci\u00f3n de ca\u00eddas<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cfba952 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"cfba952\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3daa056 elementor-widget elementor-widget-menu-anchor\" data-id=\"3daa056\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"fpvideos\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf1d9b9 elementor-widget elementor-widget-heading\" data-id=\"bf1d9b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">V\u00eddeos de prevenci\u00f3n de ca\u00eddas<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4dd0a72 elementor-widget elementor-widget-text-editor\" data-id=\"4dd0a72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: rgb(0, 128, 128);\">\" <\/span><a href=\"http:\/\/ourventura.com\/fall-prevention-for-older-adults\/\" target=\"_blank\" rel=\"noopener noreferrer\" style=\"background-color: rgb(255, 255, 255);\">MIRA: <em>Prevenci\u00f3n de ca\u00eddas para personas mayores (Our Ventura TV - julio 2020)<\/em><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-18b4db8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"18b4db8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c93dd29\" data-id=\"c93dd29\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2106c9e elementor-widget elementor-widget-video\" data-id=\"2106c9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/MX2vV-PQ0WQ&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e4960c1\" data-id=\"e4960c1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d3ebc9e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d3ebc9e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-af1d14c\" data-id=\"af1d14c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-85d36df elementor-widget elementor-widget-video\" data-id=\"85d36df\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/vUmqJ6jta4k&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-18b8c26\" data-id=\"18b8c26\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cdda50a elementor-widget elementor-widget-video\" data-id=\"cdda50a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/geRU-ZRscBY&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-611bc84 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"611bc84\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7fdce74\" data-id=\"7fdce74\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3cd33a4 elementor-widget elementor-widget-video\" data-id=\"3cd33a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/c4zBR0lOmLg&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-35a254e\" data-id=\"35a254e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f29395f elementor-widget elementor-widget-video\" data-id=\"f29395f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/R75nByLVK2o&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fc1035a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fc1035a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c0a20ba\" data-id=\"c0a20ba\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-61b1433 elementor-widget elementor-widget-video\" data-id=\"61b1433\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/qgy2kG9Ak4s&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5f0691d\" data-id=\"5f0691d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dd514d0 elementor-widget elementor-widget-video\" data-id=\"dd514d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/zFSht7hYTnQ&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-379f252 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"379f252\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5b63630\" data-id=\"5b63630\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f017c5 elementor-widget elementor-widget-video\" data-id=\"5f017c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/_2ChApHZzWM&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-38191c9\" data-id=\"38191c9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-42d7641 elementor-widget elementor-widget-video\" data-id=\"42d7641\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/pwjlGx-Mrtk&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>El Foro de Prevenci\u00f3n de Ca\u00eddas regresar\u00e1 el viernes 27 de septiembre de 2024 al campus de la Universidad Cal Lutheran.\u00a0<\/p>","protected":false},"author":2,"featured_media":0,"parent":207,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","footnotes":""},"class_list":["post-710","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/vcaaa.venturacounty.gov\/es\/wp-json\/wp\/v2\/pages\/710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vcaaa.venturacounty.gov\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/vcaaa.venturacounty.gov\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/vcaaa.venturacounty.gov\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/vcaaa.venturacounty.gov\/es\/wp-json\/wp\/v2\/comments?post=710"}],"version-history":[{"count":0,"href":"https:\/\/vcaaa.venturacounty.gov\/es\/wp-json\/wp\/v2\/pages\/710\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/vcaaa.venturacounty.gov\/es\/wp-json\/wp\/v2\/pages\/207"}],"wp:attachment":[{"href":"https:\/\/vcaaa.venturacounty.gov\/es\/wp-json\/wp\/v2\/media?parent=710"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}